{"id":95795,"date":"2026-09-01T17:59:36","date_gmt":"2026-09-01T21:59:36","guid":{"rendered":"https:\/\/mrhome.com.do\/?post_type=propiedad&#038;p=95795"},"modified":"2026-09-01T17:59:36","modified_gmt":"2026-09-01T21:59:36","slug":"se-vende-apartamento-en-el-millon-419657","status":"publish","type":"propiedad","link":"https:\/\/mrhome.com.do\/en\/propiedad\/se-vende-apartamento-en-el-millon-419657\/","title":{"rendered":"Se vende Apartamento en el Millon"},"content":{"rendered":"<p>EL MILL\u00d3N, se vende hermoso apartamento, en zona buena. A una esquina de la N\u00fa\u00f1ez, cerca de todo, totalmente remodelado, decorado y climatizado completo. \u00a1UNA BELLEZA!<\/p>\n<p>. <\/p>\n<p>Descripci\u00f3n: <\/p>\n<p>181 metros (3er. Piso)<\/p>\n<p>3 habs. (cada una con su ba\u00f1o).<\/p>\n<p>3 \u00bd Ba\u00f1os.<\/p>\n<p>Sala, Comedor separado <\/p>\n<p>Cocina en Roble Brasile\u00f1o cerrada <\/p>\n<p>\u00c1rea de lavado, Hab. de servicio. <\/p>\n<p>2 Parqueos techados <\/p>\n<p>Sistema de alarma.<\/p>\n<p>Puerta principal Multilok blindada<\/p>\n<p>Shuttle en todas las ventanas y balc\u00f3n <\/p>\n<p>Vigilante 24 horas. Circuito de c\u00e1maras <\/p>\n<p>Circuito de alarma y alarma contra incendio <\/p>\n<p>Ascensor, Planta Full, <\/p>\n<p>Paredes en estucado<\/p>\n<p>Cisterna\/Pozo\/Calentador\/Gas Com\u00fan<\/p>\n<p>Gym, \u00e1rea de juegos para ni\u00f1os<\/p>\n<p>.<\/p>\n<p>.<\/p>\n<p>El precio incluye:<\/p>\n<p>\u2714Aires en todas las \u00e1reas (4 en total todos inverter )<\/p>\n<p>\u2714Sistema de alarmas \ud83d\udea8<\/p>\n<p>\u2714Sistema de c\u00e1maras \ud83c\udfa5<\/p>\n<p>\u2714Sistema contra Incendio<\/p>\n<p>\u2714Shuttles en todas las ventanas y balc\u00f3n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hermoso apartamento en El Mill\u00f3n, ubicado a esquina de la N\u00fa\u00f1ez, totalmente remodelado, decorado y climatizado. Cuenta con 181 m\u00b2, tres habitaciones con ba\u00f1o, cocina en roble brasile\u00f1o, dos parqueos, seguridad 24\/7, ascensor, planta full, \u00e1reas sociales, gimnasio, juegos para ni\u00f1os y sistemas de alarma, c\u00e1maras y contra incendios integrados.<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false},"categories":[],"tags":[],"desarrollador":[],"comprar-propiedades":[45],"operacion":[3],"tipo-de-inmueble":[6],"provincia":[15],"ciudad":[16],"sector":[291],"class_list":["post-95795","propiedad","type-propiedad","status-publish","hentry","comprar-propiedades-listo","operacion-comprar","tipo-de-inmueble-apartamentos","provincia-santo-domingo-de-guzman","ciudad-santo-domingo-d-n","sector-el-millon"],"acf":{"amenidades_del_inmueble":[{"nombre":"Aire acondicionado","icono":""},{"nombre":"\u00c1rea Infantil","icono":""},{"nombre":"C\u00e1maras de seguridad","icono":""},{"nombre":"Cocina Caliente","icono":""},{"nombre":"Gas com\u00fan","icono":""},{"nombre":"Gimnasio","icono":""},{"nombre":"Lobby","icono":""},{"nombre":"madera: roble brasile\u00f1o","icono":""}]},"_links":{"self":[{"href":"https:\/\/mrhome.com.do\/en\/wp-json\/wp\/v2\/propiedad\/95795","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mrhome.com.do\/en\/wp-json\/wp\/v2\/propiedad"}],"about":[{"href":"https:\/\/mrhome.com.do\/en\/wp-json\/wp\/v2\/types\/propiedad"}],"wp:attachment":[{"href":"https:\/\/mrhome.com.do\/en\/wp-json\/wp\/v2\/media?parent=95795"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mrhome.com.do\/en\/wp-json\/wp\/v2\/categories?post=95795"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mrhome.com.do\/en\/wp-json\/wp\/v2\/tags?post=95795"},{"taxonomy":"desarrollador","embeddable":true,"href":"https:\/\/mrhome.com.do\/en\/wp-json\/wp\/v2\/desarrollador?post=95795"},{"taxonomy":"comprar-propiedades","embeddable":true,"href":"https:\/\/mrhome.com.do\/en\/wp-json\/wp\/v2\/comprar-propiedades?post=95795"},{"taxonomy":"operacion","embeddable":true,"href":"https:\/\/mrhome.com.do\/en\/wp-json\/wp\/v2\/operacion?post=95795"},{"taxonomy":"tipo-de-inmueble","embeddable":true,"href":"https:\/\/mrhome.com.do\/en\/wp-json\/wp\/v2\/tipo-de-inmueble?post=95795"},{"taxonomy":"provincia","embeddable":true,"href":"https:\/\/mrhome.com.do\/en\/wp-json\/wp\/v2\/provincia?post=95795"},{"taxonomy":"ciudad","embeddable":true,"href":"https:\/\/mrhome.com.do\/en\/wp-json\/wp\/v2\/ciudad?post=95795"},{"taxonomy":"sector","embeddable":true,"href":"https:\/\/mrhome.com.do\/en\/wp-json\/wp\/v2\/sector?post=95795"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}